{"id":390,"date":"2019-01-08T21:54:47","date_gmt":"2019-01-08T21:54:47","guid":{"rendered":"https:\/\/almudenabulani.com\/?page_id=390"},"modified":"2025-02-18T10:31:50","modified_gmt":"2025-02-18T09:31:50","slug":"wedding-officiant","status":"publish","type":"page","link":"https:\/\/almudenabulani.com\/en\/wedding-officiant\/","title":{"rendered":"Wedding Officiant"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"390\" class=\"elementor elementor-390\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b40dbf e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"4b40dbf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae112e5 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ae112e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Servicios<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92153d1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"92153d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Almudena Bulani<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d03f23 elementor-button-outline elementor-align-center elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3d03f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"32\" viewBox=\"0 0 20 32\"><path d=\"M18.614 14.841l-13.091-13.091c-0.773-0.636-1.545-0.636-2.318 0-0.636 0.773-0.636 1.545 0 2.318l11.932 11.932-11.932 11.932c-0.636 0.773-0.636 1.545 0 2.318 0.773 0.637 1.545 0.637 2.318 0l13.091-13.091c0.636-0.773 0.636-1.545 0-2.318z\" class=\"btn-icon__icon\"><\/path><path d=\"M18.614 14.841l-13.091-13.091c-0.773-0.636-1.545-0.636-2.318 0-0.636 0.773-0.636 1.545 0 2.318l11.932 11.932-11.932 11.932c-0.636 0.773-0.636 1.545 0 2.318 0.773 0.637 1.545 0.637 2.318 0l13.091-13.091c0.636-0.773 0.636-1.545 0-2.318z\" class=\"btn-icon__icon\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver Bodas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ee0f9b e-flex e-con-boxed e-con e-parent\" data-id=\"4ee0f9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b600caa elementor-widget elementor-widget-ucaddon_animated_mouse_scroll_icon\" data-id=\"b600caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_animated_mouse_scroll_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Animated Mouse Scroll Icon -->\n<style>\/* widget: Animated Mouse Scroll Icon *\/\n\n.mousey {\n  border-style:solid;\n  box-sizing: border-box;\n  display:inline-block;\n  text-align:center;\n}\n.scroller {\n  border-radius: 50px;\n  animation-name: scroll;\n  animation-duration: 2.2s;\n  animation-timing-function: cubic-bezier(.15,.41,.69,.94);\n  animation-iteration-count: infinite;\n  display:inline-block;\n}\n@keyframes scroll {\n  0% { opacity: 0; }\n  10% { transform: translateY(0); opacity: 1; }\n  100% { transform: translateY(15px); opacity: 0;}\n}\n\n<\/style>\n\n<div class=\"scroll-downs\" style=\"text-align:center;\">\n  <a href=\"#inicio\" >\t\n  <div class=\"mousey\">\n    <div class=\"scroller\"><\/div>\n  <\/div>\n  <\/a>\t\n<\/div>\n<!-- end Animated Mouse Scroll Icon -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcf0968 e-flex e-con-boxed e-con e-parent\" data-id=\"dcf0968\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67118f2 e-con-full e-flex e-con e-child\" data-id=\"67118f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-655dd7b elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"655dd7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769.jpg\" class=\"attachment-full size-full wp-image-20497\" alt=\"\" srcset=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769.jpg 300w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769.jpg 1024w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769.jpg 768w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769-18x12.jpg 18w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-358-de-769.jpg 1500w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce39ff9 e-con-full e-flex e-con e-child\" data-id=\"ce39ff9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e0b91e9 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e0b91e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a2f4d6 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9a2f4d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-986bbbc elementor-widget elementor-widget-heading\" data-id=\"986bbbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">MAESTRO DE CEREMONIAS<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b9c4a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"56b9c4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oficiante de Bodas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3a442f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b3a442f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El servido de oficiante de bodas, est\u00e1 dirigido a aquellas parejas que necesitan un maestro de ceremonias para su boda civil, simb\u00f3lica o blessing.<\/p><p>La oficiante se reunir\u00e1 con la pareja y compartir\u00e9is con ella vuestra historia. Con esta informaci\u00f3n la oficiante podr\u00e1 establecer el tono de la ceremonia y escribir un gui\u00f3n personalizado para vosotros.<\/p><p>Una semana antes de la boda, realizar\u00e9is un ensayo general para estar listos para el gran d\u00eda. El d\u00eda de la boda, se encargar\u00e1 de oficiar vuestra ceremonia con profesionalidad y cercan\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ee6311 e-flex e-con-boxed e-con e-parent\" data-id=\"5ee6311\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-947ed55 e-con-full e-flex e-con e-child\" data-id=\"947ed55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-566fb33 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"566fb33\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e860d5 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6e860d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0075d87 elementor-widget elementor-widget-heading\" data-id=\"0075d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">OFICIANTE DE BODAS<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d244fd7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d244fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo Trabajamos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a5ffc elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"30a5ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Etapa inicial:<\/p><ul><li>Reuni\u00f3n con la pareja.<\/li><li>Compart\u00eds con nosotros vuestra historia.<\/li><li>Establecemos el tono de la ceremonia, la estructura y la duraci\u00f3n.<\/li><li>Escribimos un gui\u00f3n personalizado para vosotros.<\/li><li>Os asesoramos de todos los aspectos t\u00e9cnicos y protocolarios de la ceremonia.<\/li><\/ul><p>Etapa final:<\/p><ul><li>Una semana antes de la boda, hacemos un ensayo general.<\/li><li>El d\u00eda de la boda coordinaremos y oficiaremos la ceremonia.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80ced0c e-con-full e-flex e-con e-child\" data-id=\"80ced0c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db7278d elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"db7278d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769.jpg\" class=\"attachment-full size-full wp-image-20498\" alt=\"\" srcset=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769.jpg 300w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769.jpg 1024w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769.jpg 768w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769-18x12.jpg 18w, https:\/\/almudenabulani.com\/wp-content\/uploads\/2025\/02\/bodcyr-451-de-769.jpg 1500w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2541ecd e-flex e-con-boxed e-con e-parent\" data-id=\"2541ecd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c19444 elementor-widget elementor-widget-shortcode\" data-id=\"4c19444\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"20337\" class=\"elementor elementor-20337\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-f5db9ab e-con-full e-flex e-con e-parent\" data-id=\"f5db9ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57c36c0 e-con-full e-flex e-con e-child\" data-id=\"57c36c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-745927a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"745927a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras Bodas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0bc952 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b0bc952\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Portfolio<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d102382 e-grid e-con-full e-con e-child\" data-id=\"d102382\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1402c4e elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"1402c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_1402c4e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_1402c4e\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/jardines-caballo-blanco-almudena-bulani23.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Courtney y Ahmad<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Jardines Caballo Blanco<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-jardines-caballo-blanco-courtney-y-ahmad\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4c265 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"ef4c265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_ef4c265 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_ef4c265\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/boda-soto-de-roma-almudena-bulani21-1.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Atlanta y V\u00edctor<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Soto de Roma<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-soto-de-roma-atlanta-y-victor\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee58722 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"ee58722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_ee58722 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_ee58722\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/mas-torraella-almudena-bulani42.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Kristina y Ali<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Mas Torraella<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-mas-torraella-kristina-y-ali\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29307c5 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"29307c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_29307c5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_29307c5\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/boda-carmen-martires-almudena-bulani31-1.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Monica y Pierre<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Carmen de los M\u00e1rtires<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-carmen-de-los-martires-monica-y-pierre\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a88596d elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"a88596d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_a88596d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_a88596d\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/Boda-Abadia-Sacromonte-Almudena-Bulani33.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Lola y Luca<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en la abad\u00eda del Sacromonte<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-abadia-sacromonte-lola-luca\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd4654f elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"fd4654f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_fd4654f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_fd4654f\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/boda-con-vistas-a-la-alhambra-palacio-de-los-cordova-almudena-bulani-81-2.gif);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Chloe y Pablo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en el Palacio de los Cordova<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-palacio-cordova-chloe-pablo\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8f59d elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"bb8f59d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_bb8f59d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_bb8f59d\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/Boda-Martires-Almudena-Bulani16.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Laura y Chris<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Carmen de los M\u00e1rtires<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-carmen-de-los-martires-laura-y-chris\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc8a113 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"dc8a113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_dc8a113 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_dc8a113\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/Boda-Chapiteles-Almudena-Bulani19.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Annmarie y Jose<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda en Carmen de los Chapiteles<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-en-carmen-de-los-chapiteles-annmarie-y-jose\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-554da06 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"554da06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Reveal on Hover -->\n<style>\/* widget: Content Reveal on Hover *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n}\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_554da06 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_554da06\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Ana-Jose-wedding-356-fotor-2024122084137.png);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Ana Mar\u00eda y Dami\u00e1n<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>Boda \u00edntima con vistas a la Alhambra<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/almudenabulani.com\/boda-intima-con-vistas-a-la-alhambra\/\" class=\"uc_btn\" >Ver m\u00e1s<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Reveal on Hover -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba514c6 elementor-align-center elementor-button-default elementor-widget elementor-widget-button\" data-id=\"ba514c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/portfolio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todas nuestras Bodas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e216887 e-con-full e-flex e-con e-parent\" data-id=\"e216887\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10979e8 elementor-widget elementor-widget-shortcode\" data-id=\"10979e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17183\" class=\"elementor elementor-17183\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-17eee1e e-flex e-con-boxed e-con e-parent\" data-id=\"17eee1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13aaec1 elementor-widget elementor-widget-image-carousel\" data-id=\"13aaec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;10&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio1.png\" alt=\"almudenabulani_premio1\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/badge-rated-100.png\" alt=\"badge-rated-100\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio3.jpg\" alt=\"almudenabulani_premio3\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio6.jpg\" alt=\"almudenabulani_premio6\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio5.jpg\" alt=\"almudenabulani_premio5\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio4.jpg\" alt=\"almudenabulani_premio4\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/badge-weddingawards_es_ES.jpg\" alt=\"badge-weddingawards_es_ES\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio7.jpeg\" alt=\"almudenabulani_premio7\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/08\/almudenabulani_premio8.png\" alt=\"almudenabulani_premio8\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/09\/badge_white_es.png\" alt=\"badge_white_es\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b839555 e-con-full e-flex e-con e-parent\" data-id=\"b839555\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5201a1d elementor-widget elementor-widget-shortcode\" data-id=\"5201a1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17189\" class=\"elementor elementor-17189\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-a9c4894 e-flex e-con-boxed e-con e-parent\" data-id=\"a9c4894\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7946f22 e-con-full e-flex e-con e-child\" data-id=\"7946f22\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a111b4e e-con-full e-flex e-con e-child\" data-id=\"a111b4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-56f5571 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"56f5571\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-scale-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b98fae9 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b98fae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7b3f43 elementor-widget elementor-widget-heading\" data-id=\"f7b3f43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Atenci\u00f3n personalizada<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8a6c0 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b8a6c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a756d2 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2a756d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfListos para comenzar a organizar el d\u00eda m\u00e1s importante de vuestras vidas?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a98525 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4a98525\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rellena el siguiente formulario y nos pondremos en contacto con vosotros lo antes posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4428b39 elementor-widget__width-initial elementor-widget elementor-widget-wpforms\" data-id=\"4428b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-elementor-widget-4428b39\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-4428b39 {\n\t\t\t\t--wpforms-button-border-radius: 100px;\n--wpforms-button-background-color: #B2920B;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 20px;\n--wpforms-button-size-height: 48px;\n--wpforms-button-size-padding-h: 20px;\n--wpforms-button-size-margin-top: 15px;\n\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-20536\"><form id=\"wpforms-form-20536\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"20536\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/390\" data-token=\"c4aa759ea5cbc863d78fcb3747aee91f\" data-token-time=\"1778659724\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-20536-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-20536-field_1\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-20536-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-20536-field_1-error\" required><\/div><div id=\"wpforms-20536-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-20536-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-20536-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-20536-field_2-error\" required><\/div><div id=\"wpforms-20536-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-20536-field_3\">Mensaje <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-20536-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-20536-field_3-error\" required><\/textarea><\/div><div id=\"wpforms-20536-field_4-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"4\"><label class=\"wpforms-field-label\">Acuerdo RGPD <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-20536-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-20536-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Doy mi consentimiento para que se almacenen mis datos y puedan responder a mi petici\u00f3n.\" aria-errormessage=\"wpforms-20536-field_4_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-20536-field_4_1\">Doy mi consentimiento para que se almacenen mis datos y puedan responder a mi petici\u00f3n.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdnDEgsAAAAAJOqDr-VN-hubgom_5sWOh_gsRc9\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"20536\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/pages\/390\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-20536\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/almudenabulani.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f31c02 e-con-full e-flex e-con e-parent\" data-id=\"5f31c02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcd6337 elementor-widget elementor-widget-shortcode\" data-id=\"fcd6337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17195\" class=\"elementor elementor-17195\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-a4a3470 e-flex e-con-boxed e-con e-parent\" data-id=\"a4a3470\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b53a3ad e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b53a3ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fa622dd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"fa622dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e641a2 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5e641a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f978acb elementor-widget elementor-widget-heading\" data-id=\"f978acb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Nuestra inspiraci\u00f3n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c4c597 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1c4c597\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79ba6d3 elementor-button-default elementor-widget elementor-widget-button\" data-id=\"79ba6d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.instagram.com\/almudenabulani\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">@almudenabulani<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a22ff78 elementor-widget elementor-widget-image-carousel\" data-id=\"a22ff78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123943.png\" alt=\"Captura de pantalla 2024-12-17 123943\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123929.png\" alt=\"Captura de pantalla 2024-12-17 123929\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123912.png\" alt=\"Captura de pantalla 2024-12-17 123912\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123527.png\" alt=\"Captura de pantalla 2024-12-17 123527\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123505.png\" alt=\"Captura de pantalla 2024-12-17 123505\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/almudenabulani.com\/wp-content\/uploads\/2024\/12\/Captura-de-pantalla-2024-12-17-123444.png\" alt=\"Captura de pantalla 2024-12-17 123444\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Servicios Almudena Bulani Ver Bodas MAESTRO DE CEREMONIAS Oficiante de Bodas El servido de oficiante de bodas, est\u00e1 dirigido a aquellas parejas que necesitan un maestro de ceremonias para su boda civil, simb\u00f3lica o blessing. La oficiante se reunir\u00e1 con la pareja y compartir\u00e9is con ella vuestra historia. Con esta informaci\u00f3n la oficiante podr\u00e1 establecer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"iawp_total_views":339,"footnotes":""},"class_list":["post-390","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/pages\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":0,"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/pages\/390\/revisions"}],"wp:attachment":[{"href":"https:\/\/almudenabulani.com\/en\/wp-json\/wp\/v2\/media?parent=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}